{"id":164,"count":23,"description":"","link":"https:\/\/alwaysbestcare.com\/worcester\/category\/dementia-care\/","name":"Dementia Care","slug":"dementia-care","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/alwaysbestcare.com\/worcester\/wp-json\/wp\/v2\/categories\/164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alwaysbestcare.com\/worcester\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/alwaysbestcare.com\/worcester\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/alwaysbestcare.com\/worcester\/wp-json\/wp\/v2\/posts?categories=164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}